{"id":291,"date":"2022-03-09T01:15:34","date_gmt":"2022-03-09T01:15:34","guid":{"rendered":"https:\/\/dracsiespases.es\/?page_id=291"},"modified":"2026-05-19T20:12:26","modified_gmt":"2026-05-19T20:12:26","slug":"proximos-eventos","status":"publish","type":"page","link":"https:\/\/dracsiespases.es\/val\/proximos-eventos\/","title":{"rendered":"Pr\u00f2xims esdeveniments"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"291\" class=\"elementor elementor-291\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-57d1e9d9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57d1e9d9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ad4155a\" data-id=\"6ad4155a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-589a3d8a elementor-widget elementor-widget-heading\" data-id=\"589a3d8a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h4 class=\"elementor-heading-title elementor-size-default\">Pr\u00f2xims esdeveniments<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3255af64 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3255af64\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b5ea66f\" data-id=\"1b5ea66f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-30f34848 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30f34848\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ccf03dd\" data-id=\"3ccf03dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52333e05 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"52333e05\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;-webkit-box-orient:horizontal;-webkit-box-direction:reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;-webkit-box-orient:horizontal;-webkit-box-direction:normal;-ms-flex-direction:row;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{-webkit-box-align:start;-ms-flex-align:start;align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{-webkit-box-align:center;-ms-flex-align:center;align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{-webkit-box-align:end;-ms-flex-align:end;align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"335\" height=\"256\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/iconoDiE.png?fit=335%2C256&amp;ssl=1\" class=\"elementor-animation-grow attachment-full size-full\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Rol en viu<\/h3><p class=\"elementor-image-box-description\">El m\u00f3n t'espera, aventurer. Ets caos o bon fer? Vine i descobrix-ho<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e7fdc5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6e7fdc5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/dracsiespases.es\/val\/rol-en-vivo\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Llegir m\u00e9s<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52e9dc8\" data-id=\"52e9dc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6de2d3f elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"6de2d3f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"335\" height=\"256\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/iconoDiE.png?fit=335%2C256&amp;ssl=1\" class=\"elementor-animation-grow attachment-full size-full\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Rol&Roll<\/h3><p class=\"elementor-image-box-description translation-block\">Nostres jornades tem\u00e0tiques. Que no t'ho compten, viu-les!<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a94d25 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0a94d25\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/dracsiespases.es\/val\/informacionrolroll\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Llegir m\u00e9s<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-39505796 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39505796\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7a7b92f1\" data-id=\"7a7b92f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c08c632 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"c08c632\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/05\/photo-69-scaled.webp?fit=2560%2C1709&amp;ssl=1\" alt=\"photo-69\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/05\/CYRIC-493-scaled.webp?fit=2560%2C1706&amp;ssl=1\" alt=\"CYRIC-493\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/05\/photo-135.webp?fit=8256%2C5504&amp;ssl=1\" alt=\"photo-135\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/05\/CYRIC-407-scaled.webp?fit=2560%2C1706&amp;ssl=1\" alt=\"CYRIC-407\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/05\/photo-215.webp?fit=8256%2C5504&amp;ssl=1\" alt=\"photo-215\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c8a7ede\" data-id=\"5c8a7ede\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4abb27a2 elementor-widget elementor-widget-heading\" data-id=\"4abb27a2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Rol en viu<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fe57427 elementor-widget elementor-widget-text-editor\" data-id=\"6fe57427\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p class=\"font_8\">Calimport es un \u00a0rol en vivo donde tendr\u00e1s que interpretar que vives y haces todo lo que har\u00eda tu personaje en el mundo de Dungeons and Dragons.<\/p><p class=\"font_8\">Basat en el m\u00f3n de Regnes Oblidats de DnD 4\u00aa edici\u00f3, durant dos dies cada jugador es ficar\u00e0 en la pell de seu personatje amb afany de diversi\u00f3 i sobretot bon ambient, on les persones compartiran eixa experi\u00e8ncia amb tu.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6ebaad elementor-countdown--label-block elementor-widget elementor-widget-countdown\" data-id=\"c6ebaad\" data-element_type=\"widget\" data-widget_type=\"countdown.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.6.3 - 28-02-2022 *\/\n.elementor-widget-countdown .elementor-countdown-expire--message{display:none;padding:20px;text-align:center}.elementor-widget-countdown .elementor-countdown-wrapper{-webkit-box-orient:horizontal;-webkit-box-direction:normal;-ms-flex-direction:row;flex-direction:row}.elementor-widget-countdown .elementor-countdown-item{padding:20px 0;text-align:center;color:#fff}.elementor-widget-countdown .elementor-countdown-digits,.elementor-widget-countdown .elementor-countdown-label{line-height:1}.elementor-widget-countdown .elementor-countdown-digits{font-size:69px}.elementor-widget-countdown .elementor-countdown-label{font-size:19px}.elementor-widget-countdown.elementor-countdown--label-block .elementor-countdown-wrapper{display:-webkit-box;display:-ms-flexbox;display:flex;-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center;margin-right:auto;margin-left:auto}.elementor-widget-countdown.elementor-countdown--label-block .elementor-countdown-digits,.elementor-widget-countdown.elementor-countdown--label-block .elementor-countdown-label{display:block}.elementor-widget-countdown.elementor-countdown--label-block .elementor-countdown-item{-ms-flex-preferred-size:0;flex-basis:0;-webkit-box-flex:1;-ms-flex-positive:1;flex-grow:1}.elementor-widget-countdown.elementor-countdown--label-inline{text-align:center}.elementor-widget-countdown.elementor-countdown--label-inline .elementor-countdown-item{display:inline-block;padding-left:5px;padding-right:5px}<\/style>\t\t<div class=\"elementor-countdown-wrapper\" data-date=\"1790359200\">\n\t\t\t<div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-days\"><\/span> <span class=\"elementor-countdown-label\">Dies<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-hours\"><\/span> <span class=\"elementor-countdown-label\">Hores<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-minutes\"><\/span> <span class=\"elementor-countdown-label\">Minuts<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-seconds\"><\/span> <span class=\"elementor-countdown-label\">Segons<\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-17f83fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17f83fb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a8b7fa3\" data-id=\"a8b7fa3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb8fb8a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"eb8fb8a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/dracsiespases.es\/val\/trasfondo-rol-en-vivo\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Informaci\u00f3<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c5c425\" data-id=\"6c5c425\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-732133e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"732133e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/dracsiespases.es\/val\/inscribirse-rol-en-vivo\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Inscribete<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a552346 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a552346\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4377da5\" data-id=\"4377da5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45927d9 elementor-widget elementor-widget-heading\" data-id=\"45927d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Rol&amp;Roll<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac73395 elementor-widget elementor-widget-text-editor\" data-id=\"ac73395\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nostres jornades de rol a Val\u00e8ncia obrin les seues portes un any m\u00e9s. Jocs de taula, manualitats, softcombat, tir amb arc, rol... Tot aquest y m\u00e9s t'espera, aix\u00ed que penja't la motxilla, viatger, i unix-te als dracs en aquesta aventura.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f99cf1 elementor-countdown--label-block elementor-widget elementor-widget-countdown\" data-id=\"9f99cf1\" data-element_type=\"widget\" data-widget_type=\"countdown.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-countdown-wrapper\" data-date=\"1808560800\">\n\t\t\t<div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-days\"><\/span> <span class=\"elementor-countdown-label\">Dies<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-hours\"><\/span> <span class=\"elementor-countdown-label\">Hores<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-minutes\"><\/span> <span class=\"elementor-countdown-label\">Minuts<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-seconds\"><\/span> <span class=\"elementor-countdown-label\">Segons<\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-c581818 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c581818\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0351e6a\" data-id=\"0351e6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36370fe elementor-align-center elementor-widget elementor-widget-button\" data-id=\"36370fe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/dracsiespases.es\/val\/informacionrolroll\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Informaci\u00f3<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c98e825\" data-id=\"c98e825\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0cef11 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"c0cef11\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/unpo.jpg?fit=960%2C720&amp;ssl=1\" alt=\"unpo\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/05\/Rol-and-Roll-2022-80-scaled.webp?fit=2560%2C1706&amp;ssl=1\" alt=\"Rol and Roll 2022-80\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/05\/Rol-and-Roll-2022-73-scaled.webp?fit=2560%2C1706&amp;ssl=1\" alt=\"Rol and Roll 2022-73\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/05\/Rol-and-Roll-2022-65-scaled.webp?fit=2560%2C1706&amp;ssl=1\" alt=\"Rol and Roll 2022-65\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/05\/Rol-and-Roll-2022-07-scaled.webp?fit=2560%2C1706&amp;ssl=1\" alt=\"Rol and Roll 2022-07\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-47cda8e0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47cda8e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-591bf4f6\" data-id=\"591bf4f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e745bbe elementor-widget elementor-widget-heading\" data-id=\"e745bbe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Activitats setmanals<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a98f80 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"7a98f80\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/mesa.jpg?fit=960%2C720&amp;ssl=1\" alt=\"mesa\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/mesa2.jpg?fit=960%2C720&amp;ssl=1\" alt=\"mesa2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-03-18-at-12.07.39.jpeg?fit=2040%2C1536&amp;ssl=1\" alt=\"WhatsApp Image 2026-03-18 at 12.07.39\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-18.21.15-1-e1779221509899.jpeg?fit=2040%2C1536&amp;ssl=1\" alt=\"WhatsApp Image 2026-05-01 at 18.21.15 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-18.21.15.jpeg?fit=2040%2C1536&amp;ssl=1\" alt=\"WhatsApp Image 2026-05-01 at 18.21.15\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-22.37.50-e1779221523535.jpeg?fit=2048%2C1152&amp;ssl=1\" alt=\"WhatsApp Image 2026-05-08 at 22.37.50\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23ec2675 elementor-widget elementor-widget-text-editor\" data-id=\"23ec2675\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Des de Dracs i Espases vos proposem un oci distint. Vine amb els teus amics, coneix a gent. Cada divendres tenim activitats noves on podreu descobrir o refor\u00e7ar habilitats i coneixements; o simplement, passar una vesprada de rialles! T'ho vas a perdre?<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-5bbb48eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bbb48eb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-709f162d\" data-id=\"709f162d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12eb9b55 elementor-widget elementor-widget-text-editor\" data-id=\"12eb9b55\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>El Casal Jove vos obri les portes, y vos oferix una infinitat d'activitats que podreu realitzar amb altres aventurers. Des de tallers de manualitats i jocs de taula, fins a convertir-te en detectiu o ser un d\u00e9u; nom\u00e9s tu tries els l\u00edmits. <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7bf2f245\" data-id=\"7bf2f245\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e1187b5 elementor-widget elementor-widget-text-editor\" data-id=\"6e1187b5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En un espai segur, on l'objectiu com\u00fa \u00e9s disfrutar i passar una bona estona. Eixe \u00e9s l'ambient que busquem des de Dracs i Espases. No ho dubtes, si vols ampliar els teus horitzons, aquest \u00e9s el teu lloc.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pr\u00f3ximos eventos Rol en vivo El mundo te espera, aventurero. \u00bfEres caos o buenhacer? Ven y desc\u00fabrelo. Leer m\u00e1s Rol&#038;Roll Nuestras jornadas tem\u00e1ticas. Que no te lo cuenten, \u00a1v\u00edvelas! Leer m\u00e1s Anterior Siguiente Rol en vivo Calimport es un \u00a0rol en vivo donde tendr\u00e1s que interpretar que vives y haces todo lo que har\u00eda tu &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/dracsiespases.es\/val\/proximos-eventos\/\"> <span class=\"screen-reader-text\">Pr\u00f2xims esdeveniments<\/span> Read More &raquo;<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","spay_email":"","footnotes":""},"class_list":["post-291","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v18.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pr\u00f3ximos eventos -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dracsiespases.es\/val\/proximos-eventos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00f3ximos eventos\" \/>\n<meta property=\"og:description\" content=\"Pr\u00f3ximos eventos Rol en vivo El mundo te espera, aventurero. \u00bfEres caos o buenhacer? Ven y desc\u00fabrelo. Leer m\u00e1s Rol&#038;Roll Nuestras jornadas tem\u00e1ticas. Que no te lo cuenten, \u00a1v\u00edvelas! Leer m\u00e1s Anterior Siguiente Rol en vivo Calimport es un \u00a0rol en vivo donde tendr\u00e1s que interpretar que vives y haces todo lo que har\u00eda tu &hellip; Pr\u00f3ximos eventos Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dracsiespases.es\/val\/proximos-eventos\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T20:12:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/iconoDiE.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/dracsiespases.es\/#organization\",\"name\":\"Dracs i espases\",\"url\":\"https:\/\/dracsiespases.es\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dracsiespases.es\/#logo\",\"inLanguage\":\"es-val\",\"url\":\"https:\/\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/logo.png\",\"contentUrl\":\"https:\/\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/logo.png\",\"width\":543,\"height\":548,\"caption\":\"Dracs i espases\"},\"image\":{\"@id\":\"https:\/\/dracsiespases.es\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dracsiespases.es\/#website\",\"url\":\"https:\/\/dracsiespases.es\/\",\"name\":\"\",\"description\":\"Asociaci\u00f3n\",\"publisher\":{\"@id\":\"https:\/\/dracsiespases.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dracsiespases.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-val\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dracsiespases.es\/proximos-eventos\/#primaryimage\",\"inLanguage\":\"es-val\",\"url\":\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/iconoDiE.png?fit=335%2C256&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/iconoDiE.png?fit=335%2C256&ssl=1\",\"width\":335,\"height\":256},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dracsiespases.es\/proximos-eventos\/#webpage\",\"url\":\"https:\/\/dracsiespases.es\/proximos-eventos\/\",\"name\":\"Pr\u00f3ximos eventos -\",\"isPartOf\":{\"@id\":\"https:\/\/dracsiespases.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dracsiespases.es\/proximos-eventos\/#primaryimage\"},\"datePublished\":\"2022-03-09T01:15:34+00:00\",\"dateModified\":\"2026-05-19T20:12:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dracsiespases.es\/proximos-eventos\/#breadcrumb\"},\"inLanguage\":\"es-val\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dracsiespases.es\/proximos-eventos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dracsiespases.es\/proximos-eventos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dracsiespases.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00f3ximos eventos\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pr\u00f3ximos eventos -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dracsiespases.es\/val\/proximos-eventos\/","og_locale":"es_ES","og_type":"article","og_title":"Pr\u00f3ximos eventos","og_description":"Pr\u00f3ximos eventos Rol en vivo El mundo te espera, aventurero. \u00bfEres caos o buenhacer? Ven y desc\u00fabrelo. Leer m\u00e1s Rol&#038;Roll Nuestras jornadas tem\u00e1ticas. Que no te lo cuenten, \u00a1v\u00edvelas! Leer m\u00e1s Anterior Siguiente Rol en vivo Calimport es un \u00a0rol en vivo donde tendr\u00e1s que interpretar que vives y haces todo lo que har\u00eda tu &hellip; Pr\u00f3ximos eventos Read More &raquo;","og_url":"https:\/\/dracsiespases.es\/val\/proximos-eventos\/","article_modified_time":"2026-05-19T20:12:26+00:00","og_image":[{"url":"https:\/\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/iconoDiE.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/dracsiespases.es\/#organization","name":"Dracs i espases","url":"https:\/\/dracsiespases.es\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/dracsiespases.es\/#logo","inLanguage":"es-val","url":"https:\/\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/logo.png","contentUrl":"https:\/\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/logo.png","width":543,"height":548,"caption":"Dracs i espases"},"image":{"@id":"https:\/\/dracsiespases.es\/#logo"}},{"@type":"WebSite","@id":"https:\/\/dracsiespases.es\/#website","url":"https:\/\/dracsiespases.es\/","name":"","description":"Asociaci\u00f3n","publisher":{"@id":"https:\/\/dracsiespases.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dracsiespases.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-val"},{"@type":"ImageObject","@id":"https:\/\/dracsiespases.es\/proximos-eventos\/#primaryimage","inLanguage":"es-val","url":"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/iconoDiE.png?fit=335%2C256&ssl=1","contentUrl":"https:\/\/i0.wp.com\/dracsiespases.es\/wp-content\/uploads\/2022\/03\/iconoDiE.png?fit=335%2C256&ssl=1","width":335,"height":256},{"@type":"WebPage","@id":"https:\/\/dracsiespases.es\/proximos-eventos\/#webpage","url":"https:\/\/dracsiespases.es\/proximos-eventos\/","name":"Pr\u00f3ximos eventos -","isPartOf":{"@id":"https:\/\/dracsiespases.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dracsiespases.es\/proximos-eventos\/#primaryimage"},"datePublished":"2022-03-09T01:15:34+00:00","dateModified":"2026-05-19T20:12:26+00:00","breadcrumb":{"@id":"https:\/\/dracsiespases.es\/proximos-eventos\/#breadcrumb"},"inLanguage":"es-val","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dracsiespases.es\/proximos-eventos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dracsiespases.es\/proximos-eventos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dracsiespases.es\/"},{"@type":"ListItem","position":2,"name":"Pr\u00f3ximos eventos"}]}]}},"_links":{"self":[{"href":"https:\/\/dracsiespases.es\/val\/wp-json\/wp\/v2\/pages\/291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dracsiespases.es\/val\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dracsiespases.es\/val\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dracsiespases.es\/val\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dracsiespases.es\/val\/wp-json\/wp\/v2\/comments?post=291"}],"version-history":[{"count":216,"href":"https:\/\/dracsiespases.es\/val\/wp-json\/wp\/v2\/pages\/291\/revisions"}],"predecessor-version":[{"id":6648,"href":"https:\/\/dracsiespases.es\/val\/wp-json\/wp\/v2\/pages\/291\/revisions\/6648"}],"wp:attachment":[{"href":"https:\/\/dracsiespases.es\/val\/wp-json\/wp\/v2\/media?parent=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}